{"id":674,"date":"2026-08-25T15:34:37","date_gmt":"2026-08-25T15:34:37","guid":{"rendered":"https:\/\/popikids.com\/product\/pegaso-premium\/"},"modified":"2026-08-28T14:09:54","modified_gmt":"2026-08-28T14:09:54","slug":"pegaso-premium","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/pegaso-premium\/","title":{"rendered":"PEGASO PREMIUM"},"content":{"rendered":"<p>Polo \u00e0 manches courtes avec traitement anti-boulochage. Point piqu\u00e9. Col et manches tiss\u00e9s en 1&#215;1 avec d\u00e9tail en relief. Patte de boutonnage \u00e0 3\u00a0boutons. Encolure bord\u00e9e de tissu assorti. Fentes lat\u00e9rales \u00e0 l&rsquo;ourlet. Poche, en option. Lavable \u00e0 60\u00a0\u00b0C.<br \/>\nComposition: 60% coton \/ 40% polyester, maille piqu\u00e9e.<br \/>\nCouleur: 190 g\/m\u00b2. Blanc: 220 g\/m\u00b2.<br \/>\nRemarks: * \u00c9tiquette D\u00e9tachable.<br \/>\n* Disponible en taille enfant.<br \/>\n* D\u00fao concept.<br \/>\n* Traitement ANTI-BOULOCHE.<br \/>\n<img decoding=\"async\" src=\"https:\/\/static.gorfactory.es\/pics\/measures\/PO_MC_HO.jpg\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Polo \u00e0 manches courtes avec traitement anti-boulochage. Point piqu\u00e9. Col et manches tiss\u00e9s en 1&#215;1 avec d\u00e9tail en relief. Patte de boutonnage \u00e0 3\u00a0boutons. Encolure bord\u00e9e de tissu assorti. Fentes lat\u00e9rales \u00e0 l&rsquo;ourlet. Poche, en option. Lavable \u00e0 60\u00a0\u00b0C. Composition: 60% coton \/ 40% polyester, maille piqu\u00e9e. Couleur: 190 g\/m\u00b2. Blanc: 220 g\/m\u00b2. Remarks: * [&hellip;]<\/p>\n","protected":false},"featured_media":676,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[38,113,121,35,34],"product_tag":[],"class_list":["post-674","product","type-product","status-publish","has-post-thumbnail","product_cat-basic","product_cat-pol_s","product_cat-pmc","product_cat-cam_po","product_cat-workwear","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/676"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=674"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=674"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=674"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}