{"id":4931,"date":"2026-09-01T16:52:50","date_gmt":"2026-09-01T16:52:50","guid":{"rendered":"https:\/\/popikids.com\/product\/elanio\/"},"modified":"2026-09-01T16:53:09","modified_gmt":"2026-09-01T16:53:09","slug":"elanio","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/elanio\/","title":{"rendered":"ELANIO"},"content":{"rendered":"<p>Sac \u00e0 dos pour enfants \u00e0 cordelettes pliable en polyester 190T. Poche pour pliage en forme d&rsquo; animal. <br \/>Composition: Polyester 190T<br \/>Remarks: Information de marquage:F(1), G(1)<\/p>","protected":false},"excerpt":{"rendered":"<p>Sac \u00e0 dos pour enfants \u00e0 cordelettes pliable en polyester 190T. Poche pour pliage en forme d&rsquo; animal. Composition: Polyester 190TRemarks: Information de marquage:F(1), G(1)<\/p>","protected":false},"featured_media":4932,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[399,448,436,437,440,439,395],"product_tag":[],"class_list":["post-4931","product","type-product","status-publish","has-post-thumbnail","product_cat-all_merchandising","product_cat-drawstring_bag","product_cat-bags_travel","product_cat-bags_travel_backpack","product_cat-all_bags_travel_bagpack","product_cat-all_bags_travel","product_cat-stamina","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/4931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=4931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/4932"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=4931"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=4931"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=4931"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=4931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}