{"id":4887,"date":"2026-09-01T16:45:47","date_gmt":"2026-09-01T16:45:47","guid":{"rendered":"https:\/\/popikids.com\/product\/balax\/"},"modified":"2026-09-01T16:46:15","modified_gmt":"2026-09-01T16:46:15","slug":"balax","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/balax\/","title":{"rendered":"BALAX"},"content":{"rendered":"<p>Bidon thermique en acier inoxydable 304 avec double paroi et isolation en cuivre sous vide, pour garder vos boissons froides ou chaudes plus longtemps. Capacit\u00e9 de 550 ml.<br \/>\nCouleur blanche adapt\u00e9e \u00e0 la sublimation. <br \/>Composition: Acier inoxydable 304. <br \/>Remarks: Capacit\u00e9 thermique\u00a0: garde les boissons chaudes pendant 12\u00a0heures et froides pendant 48\u00a0heures.<br \/>\nSyst\u00e8me anti-gouttes.<br \/>\nPr\u00e9sentation en bo\u00eete design.<br \/>\nPasse au lave-vaisselle.<br \/>\nNous vous recommandons de le laver \u00e0 la main. <\/p>","protected":false},"excerpt":{"rendered":"<p>Bidon thermique en acier inoxydable 304 avec double paroi et isolation en cuivre sous vide, pour garder vos boissons froides ou chaudes plus longtemps. Capacit\u00e9 de 550 ml. Couleur blanche adapt\u00e9e \u00e0 la sublimation. Composition: Acier inoxydable 304. Remarks: Capacit\u00e9 thermique\u00a0: garde les boissons chaudes pendant 12\u00a0heures et froides pendant 48\u00a0heures. Syst\u00e8me anti-gouttes. Pr\u00e9sentation en [&hellip;]<\/p>\n","protected":false},"featured_media":4888,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[404,417,416,396,399,395,421,400],"product_tag":[],"class_list":["post-4887","product","type-product","status-publish","has-post-thumbnail","product_cat-bottles_thermos_flas","product_cat-thermos_flasks","product_cat-all_bottle_thermos_flash","product_cat-eating_drinkware","product_cat-all_merchandising","product_cat-stamina","product_cat-sublimation","product_cat-all_eating_drinkware","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/4887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=4887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/4888"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=4887"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=4887"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=4887"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=4887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}