{"id":4823,"date":"2026-09-01T16:44:34","date_gmt":"2026-09-01T16:44:34","guid":{"rendered":"https:\/\/popikids.com\/product\/kelis\/"},"modified":"2026-09-01T16:44:51","modified_gmt":"2026-09-01T16:44:51","slug":"kelis","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/kelis\/","title":{"rendered":"KELIS"},"content":{"rendered":"<p>Bouteille thermos \u00e0 double paroi avec corps en acier inoxydable 304 recycl\u00e9. Capacit\u00e9\u00a0: 700\u00a0ml Avec poign\u00e9e de transport et paille extensible suppl\u00e9mentaire. Bouchon automatique.<br \/>\n<br \/>Composition: Acier inoxydable 304 recycl\u00e9<br \/>Remarks: Ne passe pas au lave-vaisselle.<br \/>\nSyst\u00e8me anti-gouttes.<br \/>\nNous vous recommandons de le laver \u00e0 la main.<br \/>\nPr\u00e9sentation en bo\u00eete \u00e9co-conception. <\/p>","protected":false},"excerpt":{"rendered":"<p>Bouteille thermos \u00e0 double paroi avec corps en acier inoxydable 304 recycl\u00e9. Capacit\u00e9\u00a0: 700\u00a0ml Avec poign\u00e9e de transport et paille extensible suppl\u00e9mentaire. Bouchon automatique. Composition: Acier inoxydable 304 recycl\u00e9Remarks: Ne passe pas au lave-vaisselle. Syst\u00e8me anti-gouttes. Nous vous recommandons de le laver \u00e0 la main. Pr\u00e9sentation en bo\u00eete \u00e9co-conception.<\/p>","protected":false},"featured_media":4824,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[404,417,416,396,399,395,400],"product_tag":[],"class_list":["post-4823","product","type-product","status-publish","has-post-thumbnail","product_cat-bottles_thermos_flas","product_cat-thermos_flasks","product_cat-all_bottle_thermos_flash","product_cat-eating_drinkware","product_cat-all_merchandising","product_cat-stamina","product_cat-all_eating_drinkware","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/4823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=4823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/4824"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=4823"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=4823"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=4823"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=4823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}