{"id":4758,"date":"2026-09-01T15:46:07","date_gmt":"2026-09-01T15:46:07","guid":{"rendered":"https:\/\/popikids.com\/product\/comix\/"},"modified":"2026-09-01T15:46:26","modified_gmt":"2026-09-01T15:46:26","slug":"comix","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/comix\/","title":{"rendered":"COMIX"},"content":{"rendered":"<p>Bo\u00eete \u00e0 lunch d&rsquo;une capacit\u00e9 de 1,3\u00a0L en PP, avec trois compartiments ind\u00e9pendants de diff\u00e9rentes tailles qui gardent les aliments s\u00e9par\u00e9s \u00e0 tout moment. De plus, ces sections font partie d&rsquo;un compartiment principal amovible, laissant de l&rsquo;espace en bas pour ranger la fourchette et la cuill\u00e8re incluses. Il dispose d&rsquo;un bouchon rabattable avec une fermeture anti-goutte gr\u00e2ce \u00e0 la doublure en silicone \u00e0 l&rsquo;int\u00e9rieur. Ce m\u00e9canisme aide \u00e0 garder les aliments dans un \u00e9tat optimal pendant le transport. En outre, elle comprend un compartiment int\u00e9rieur s\u00e9par\u00e9 pour transporter des sauces ou d&rsquo;autres condiments. <br \/>Composition: PP, silicone<br \/>Remarks: Capacit\u00e9\u00a0: 1,3\u00a0L. Syst\u00e8me anti-gouttes.<br \/>\nPasse au micro-ondes (avec couvercle ouvert).<br \/>\nNe passe pas au lave-vaisselle.<br \/>\nNous vous recommandons de le laver \u00e0 la main. <\/p>","protected":false},"excerpt":{"rendered":"<p>Bo\u00eete \u00e0 lunch d&rsquo;une capacit\u00e9 de 1,3\u00a0L en PP, avec trois compartiments ind\u00e9pendants de diff\u00e9rentes tailles qui gardent les aliments s\u00e9par\u00e9s \u00e0 tout moment. De plus, ces sections font partie d&rsquo;un compartiment principal amovible, laissant de l&rsquo;espace en bas pour ranger la fourchette et la cuill\u00e8re incluses. Il dispose d&rsquo;un bouchon rabattable avec une fermeture [&hellip;]<\/p>\n","protected":false},"featured_media":4759,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[401,405,404,396,399,402,403,395,400],"product_tag":[],"class_list":["post-4758","product","type-product","status-publish","has-post-thumbnail","product_cat-all_take_away","product_cat-bottles","product_cat-bottles_thermos_flas","product_cat-eating_drinkware","product_cat-all_merchandising","product_cat-novelty","product_cat-all_novelty","product_cat-stamina","product_cat-all_eating_drinkware","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/4758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=4758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/4759"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=4758"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=4758"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=4758"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=4758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}