{"id":4536,"date":"2026-08-25T17:47:01","date_gmt":"2026-08-25T17:47:01","guid":{"rendered":"https:\/\/popikids.com\/product\/aida\/"},"modified":"2026-08-25T17:47:34","modified_gmt":"2026-08-25T17:47:34","slug":"aida","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/aida\/","title":{"rendered":"AIDA"},"content":{"rendered":"<p>D\u00e9bardeur technique ajust\u00e9 respirant et \u00e9lastique. Finition peau de p\u00eache. Col rond et bordures d&#8217;emmanchure ton sur ton. Dos nageur. <br \/>Composition: 92% polyester \/ 8% \u00e9lasthanne, 160 g\/m\u00b2. <br \/>Remarks: Mod\u00e8le respirant avec s\u00e9chage facil.<br \/>\n*Tacte doux.<br \/>\n*\u00c9tiquette d\u00e9tachable.<br \/>\n*Pour la couleur noir de ce mod\u00e8le on ne peut faire que de la broderie, aucun autre travail ne seras faisable. <br \/><img decoding=\"async\" src=\"https:\/\/static.gorfactory.es\/pics\/measures\/TI_MU.jpg\"><\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9bardeur technique ajust\u00e9 respirant et \u00e9lastique. Finition peau de p\u00eache. Col rond et bordures d&#8217;emmanchure ton sur ton. Dos nageur. Composition: 92% polyester \/ 8% \u00e9lasthanne, 160 g\/m\u00b2. Remarks: Mod\u00e8le respirant avec s\u00e9chage facil. *Tacte doux. *\u00c9tiquette d\u00e9tachable. *Pour la couleur noir de ce mod\u00e8le on ne peut faire que de la broderie, aucun autre [&hellip;]<\/p>\n","protected":false},"featured_media":4537,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[120,28,36,104,35,103],"product_tag":[],"class_list":["post-4536","product","type-product","status-publish","has-post-thumbnail","product_cat-cat","product_cat-sports","product_cat-t_shirts","product_cat-sp_tshi","product_cat-cam_po","product_cat-cam_sp","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/4536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=4536"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/4537"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=4536"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=4536"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=4536"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=4536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}