{"id":3757,"date":"2026-08-25T17:27:29","date_gmt":"2026-08-25T17:27:29","guid":{"rendered":"https:\/\/popikids.com\/product\/detroit\/"},"modified":"2026-08-25T17:28:13","modified_gmt":"2026-08-25T17:28:13","slug":"detroit","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/detroit\/","title":{"rendered":"DETROIT"},"content":{"rendered":"<p>T-shirt technique respirant unisexe bicolore \u00e0 manches courtes. Combinaison de tissus et de couleurs. Col rond avec biais dans le tissu principal. Coutures en point de surjet de couleur contrast\u00e9e. <br \/>Composition: Tissu face avant: 100% polyester bird&rsquo;s eye. Tissu face arri\u00e8re: 100% polyester 3D. 130 g\/m\u00b2. <br \/>Remarks: Mod\u00e8le respirant avec s\u00e9chage facil.<br \/>\n*\u00c9tiquette d\u00e9tachable.<br \/>\n*Tissu technique. <br \/><img decoding=\"async\" src=\"https:\/\/static.gorfactory.es\/pics\/measures\/CA_MC_HO.jpg\"><\/p>","protected":false},"excerpt":{"rendered":"<p>T-shirt technique respirant unisexe bicolore \u00e0 manches courtes. Combinaison de tissus et de couleurs. Col rond avec biais dans le tissu principal. Coutures en point de surjet de couleur contrast\u00e9e. Composition: Tissu face avant: 100% polyester bird&rsquo;s eye. Tissu face arri\u00e8re: 100% polyester 3D. 130 g\/m\u00b2. Remarks: Mod\u00e8le respirant avec s\u00e9chage facil. *\u00c9tiquette d\u00e9tachable. *Tissu [&hellip;]<\/p>\n","protected":false},"featured_media":3758,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[28,104,103],"product_tag":[],"class_list":["post-3757","product","type-product","status-publish","has-post-thumbnail","product_cat-sports","product_cat-sp_tshi","product_cat-cam_sp","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/3757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=3757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/3758"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=3757"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=3757"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=3757"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=3757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}