{"id":2831,"date":"2026-08-25T17:02:29","date_gmt":"2026-08-25T17:02:29","guid":{"rendered":"https:\/\/popikids.com\/product\/creta\/"},"modified":"2026-08-25T17:04:15","modified_gmt":"2026-08-25T17:04:15","slug":"creta","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/creta\/","title":{"rendered":"CRETA"},"content":{"rendered":"<p>Surv\u00eatement classique bross\u00e9 avec bandes contrast\u00e9es. Veste \u00e0 col montant avec biais \u00e0 l&rsquo;encolure. Fermeture \u00e0 glissi\u00e8re sur le devant avec tirette. Poches lat\u00e9rales avec fermeture \u00e0 glissi\u00e8re en tailles adulte. Col, poignets et taille c\u00f4tel\u00e9s 1&#215;1. Pantalons avec ceinture \u00e9lastiqu\u00e9e et cordon de serrage r\u00e9glable. Poches lat\u00e9rales et une poche arri\u00e8re passepoil\u00e9e. Panneau lat\u00e9ral de couleur contrast\u00e9e. Poignets c\u00f4tel\u00e9s 1&#215;1. <br \/>Composition: 100% polyester, tissu en ac\u00e9tate lisse, 210 g\/m\u00b2. <br \/>Remarks: *\u00c9tiquette d\u00e9tachable.<br \/>\n*Disponible en taille enfant.<br \/>\n*Dur\u00e9e dans le catalogue de 3 ans.<br \/>\n*Votre commande peut comprendre des mod\u00e8les avec poches zipp\u00e9es et non zipp\u00e9es, en fonction de la disponibilit\u00e9. <br \/><img decoding=\"async\" src=\"https:\/\/static.gorfactory.es\/pics\/measures\/CH_HO.jpg\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Surv\u00eatement classique bross\u00e9 avec bandes contrast\u00e9es. Veste \u00e0 col montant avec biais \u00e0 l&rsquo;encolure. Fermeture \u00e0 glissi\u00e8re sur le devant avec tirette. Poches lat\u00e9rales avec fermeture \u00e0 glissi\u00e8re en tailles adulte. Col, poignets et taille c\u00f4tel\u00e9s 1&#215;1. Pantalons avec ceinture \u00e9lastiqu\u00e9e et cordon de serrage r\u00e9glable. Poches lat\u00e9rales et une poche arri\u00e8re passepoil\u00e9e. Panneau lat\u00e9ral [&hellip;]<\/p>\n","protected":false},"featured_media":2832,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[28,313],"product_tag":[],"class_list":["post-2831","product","type-product","status-publish","has-post-thumbnail","product_cat-sports","product_cat-chnd","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/2831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=2831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/2832"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=2831"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=2831"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=2831"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=2831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}