{"id":2106,"date":"2026-08-25T16:42:31","date_gmt":"2026-08-25T16:42:31","guid":{"rendered":"https:\/\/popikids.com\/product\/titan\/"},"modified":"2026-08-25T16:43:49","modified_gmt":"2026-08-25T16:43:49","slug":"titan","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/titan\/","title":{"rendered":"TITAN"},"content":{"rendered":"<p>Ensemble de sport avec t-shirt \u00e0 manches courtes et short. Impression sur le panneau avant. Passepoil sur les coutures des manches raglan. D\u00e9tail en tissu maille au centre du dos, laiss\u00e9 libre pour le retraitement. Pantalon en tissu principal avec bandes lat\u00e9rales en tissu respirant. Coutures passepoil\u00e9es contrast\u00e9es. <br \/>Composition: Principal\u00a0: 100\u00a0% polyester interlock.<br \/>\nContraste\u00a0: 92\u00a0% polyester 8\u00a0% \u00e9lasthanne.<br \/>\n140\u00a0g\/m\u00b2. <br \/>Remarks: *\u00c9tiquette papier amovible.<br \/>\n*Disponible en tailles kids.<br \/>\n*Respirant.<br \/>\n*Pack ensemble sportif. <br \/><img decoding=\"async\" src=\"https:\/\/static.gorfactory.es\/pics\/measures\/CJ_HO.jpg\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Ensemble de sport avec t-shirt \u00e0 manches courtes et short. Impression sur le panneau avant. Passepoil sur les coutures des manches raglan. D\u00e9tail en tissu maille au centre du dos, laiss\u00e9 libre pour le retraitement. Pantalon en tissu principal avec bandes lat\u00e9rales en tissu respirant. Coutures passepoil\u00e9es contrast\u00e9es. Composition: Principal\u00a0: 100\u00a0% polyester interlock. Contraste\u00a0: 92\u00a0% [&hellip;]<\/p>\n","protected":false},"featured_media":2107,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[232,117,39,28],"product_tag":[],"class_list":["post-2106","product","type-product","status-publish","has-post-thumbnail","product_cat-equip","product_cat-novelty_roly","product_cat-featured_roly","product_cat-sports","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/2106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=2106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/2107"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=2106"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=2106"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=2106"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=2106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}