{"id":1898,"date":"2026-08-25T16:32:12","date_gmt":"2026-08-25T16:32:12","guid":{"rendered":"https:\/\/popikids.com\/product\/nebraska-2\/"},"modified":"2026-08-25T16:32:12","modified_gmt":"2026-08-25T16:32:12","slug":"nebraska-2","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/nebraska-2\/","title":{"rendered":"NEBRASKA"},"content":{"rendered":"<p>Veste softshell 2 couches avec fermeture \u00e0 glissi\u00e8re sur le devant. D\u00e9perlante et coupe-vent. Doubl\u00e9e de tissu micropolaire. Deux poches lat\u00e9rales et une poche poitrine droite avec fermetures \u00e0 glissi\u00e8re invers\u00e9es. Prot\u00e8ge-menton dans le m\u00eame tissu invers\u00e9. Ajusteurs lat\u00e9raux int\u00e9rieurs en tailles adultes. <br \/>Composition: Deux couches.<br \/>\nExt\u00e9rieur: 100% polyester.  Int\u00e9rieur 100% polyester micropolaire extra-chaud.  300 g\/m\u00b2. <br \/>Remarks: *Duo Concept.<br \/>\n*Disponible en tailles enfant.<br \/>\n* N&rsquo;oubliez pas les limites de ce type de tissu et la n\u00e9cessit\u00e9 d&rsquo;utiliser des encres anti-sublimation lors du marquage.<br \/>\n*L&rsquo;impression DTF n&rsquo;est pas recommand\u00e9e pour ce mod\u00e8le. <br \/><img decoding=\"async\" src=\"https:\/\/static.gorfactory.es\/pics\/measures\/SS_HO.jpg\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Veste softshell 2 couches avec fermeture \u00e0 glissi\u00e8re sur le devant. D\u00e9perlante et coupe-vent. Doubl\u00e9e de tissu micropolaire. Deux poches lat\u00e9rales et une poche poitrine droite avec fermetures \u00e0 glissi\u00e8re invers\u00e9es. Prot\u00e8ge-menton dans le m\u00eame tissu invers\u00e9. Ajusteurs lat\u00e9raux int\u00e9rieurs en tailles adultes. Composition: Deux couches. Ext\u00e9rieur: 100% polyester. Int\u00e9rieur 100% polyester micropolaire extra-chaud. 300 [&hellip;]<\/p>\n","protected":false},"featured_media":1899,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[38,118,110,34],"product_tag":[],"class_list":["post-1898","product","type-product","status-publish","has-post-thumbnail","product_cat-basic","product_cat-softshell","product_cat-coats","product_cat-workwear","first","instock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/1898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=1898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/1899"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=1898"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=1898"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=1898"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=1898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}