{"id":1316,"date":"2026-08-25T16:14:30","date_gmt":"2026-08-25T16:14:30","guid":{"rendered":"https:\/\/popikids.com\/product\/badet\/"},"modified":"2026-08-28T14:05:31","modified_gmt":"2026-08-28T14:05:31","slug":"badet","status":"publish","type":"product","link":"https:\/\/popikids.com\/en\/product\/badet\/","title":{"rendered":"BADET"},"content":{"rendered":"<p>Sweatshirt unisexe bicolore avec capuche doubl\u00e9e. Manches raglan. Poignets et taille c\u00f4tel\u00e9s 1&#215;1 avec \u00e9lasthanne. Coutures bord\u00e9es de tissu assorti. Cordon de serrage plat dans la capuche et \u0153illets en m\u00e9tal.<br \/>\nComposition: 50% coton \/ 50% polyester, maille molleton gratt\u00e9e, 280 g\/m\u00b2.<br \/>\nCouleur Gris chin\u00e9 58: 55% coton \/ 40% polyester \/ 5%viscose.<br \/>\nRemarks: *\u00c9tiquette d\u00e9tachable.<br \/>\n*Tailles enfants sans cordon de serrage.<br \/>\n<img decoding=\"async\" src=\"https:\/\/static.gorfactory.es\/pics\/measures\/SU_HO.jpg\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Sweatshirt unisexe bicolore avec capuche doubl\u00e9e. Manches raglan. Poignets et taille c\u00f4tel\u00e9s 1&#215;1 avec \u00e9lasthanne. Coutures bord\u00e9es de tissu assorti. Cordon de serrage plat dans la capuche et \u0153illets en m\u00e9tal. Composition: 50% coton \/ 50% polyester, maille molleton gratt\u00e9e, 280 g\/m\u00b2. Couleur Gris chin\u00e9 58: 55% coton \/ 40% polyester \/ 5%viscose. Remarks: *\u00c9tiquette [&hellip;]<\/p>\n","protected":false},"featured_media":1321,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[107,108,106],"product_tag":[],"class_list":["post-1316","product","type-product","status-publish","has-post-thumbnail","product_cat-swe","product_cat-swe_h","product_cat-sud_cha","first","instock","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product\/1316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/comments?post=1316"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media\/1321"}],"wp:attachment":[{"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/media?parent=1316"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_brand?post=1316"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_cat?post=1316"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/popikids.com\/en\/wp-json\/wp\/v2\/product_tag?post=1316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}